{"id":154,"count":1,"description":"","link":"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/","name":"B.B. King","slug":"b-b-king","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B.B. King Archives - BluesWave Radio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B.B. King Archives - BluesWave Radio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/\" \/>\n<meta property=\"og:site_name\" content=\"BluesWave Radio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BlueswaveRadio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/tag\\\/b-b-king\\\/\",\"url\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/tag\\\/b-b-king\\\/\",\"name\":\"B.B. King Archives - BluesWave Radio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/tag\\\/b-b-king\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/tag\\\/b-b-king\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B.B. King\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/#website\",\"url\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/\",\"name\":\"BluesWave Radio\",\"description\":\"The home of good Blues and Rock music\",\"publisher\":{\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/#organization\",\"name\":\"BluesWave Radio\",\"alternateName\":\"BWR\",\"url\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/BluesWave.Radio_.logo_.512X512.png\",\"contentUrl\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/BluesWave.Radio_.logo_.512X512.png\",\"width\":512,\"height\":512,\"caption\":\"BluesWave Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/blueswave.radio\\\/fm223\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/blueswave.radio\",\"https:\\\/\\\/x.com\\\/BlueswaveRadio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B.B. King Archives - BluesWave Radio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/","og_locale":"en_US","og_type":"article","og_title":"B.B. King Archives - BluesWave Radio","og_url":"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/","og_site_name":"BluesWave Radio","twitter_card":"summary_large_image","twitter_site":"@BlueswaveRadio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/","url":"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/","name":"B.B. King Archives - BluesWave Radio","isPartOf":{"@id":"https:\/\/blueswave.radio\/fm223\/#website"},"breadcrumb":{"@id":"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blueswave.radio\/fm223\/tag\/b-b-king\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blueswave.radio\/fm223\/"},{"@type":"ListItem","position":2,"name":"B.B. King"}]},{"@type":"WebSite","@id":"https:\/\/blueswave.radio\/fm223\/#website","url":"https:\/\/blueswave.radio\/fm223\/","name":"BluesWave Radio","description":"The home of good Blues and Rock music","publisher":{"@id":"https:\/\/blueswave.radio\/fm223\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blueswave.radio\/fm223\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blueswave.radio\/fm223\/#organization","name":"BluesWave Radio","alternateName":"BWR","url":"https:\/\/blueswave.radio\/fm223\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blueswave.radio\/fm223\/#\/schema\/logo\/image\/","url":"https:\/\/blueswave.radio\/fm223\/wp-content\/uploads\/2021\/10\/BluesWave.Radio_.logo_.512X512.png","contentUrl":"https:\/\/blueswave.radio\/fm223\/wp-content\/uploads\/2021\/10\/BluesWave.Radio_.logo_.512X512.png","width":512,"height":512,"caption":"BluesWave Radio"},"image":{"@id":"https:\/\/blueswave.radio\/fm223\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blueswave.radio","https:\/\/x.com\/BlueswaveRadio"]}]}},"_links":{"self":[{"href":"https:\/\/blueswave.radio\/fm223\/wp-json\/wp\/v2\/tags\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blueswave.radio\/fm223\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blueswave.radio\/fm223\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blueswave.radio\/fm223\/wp-json\/wp\/v2\/posts?tags=154"},{"href":"https:\/\/blueswave.radio\/fm223\/wp-json\/wp\/v2\/podcast?tags=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}